{"id":5009,"count":1,"description":"","link":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/","name":"xaouen","slug":"xaouen-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>xaouen archivos - Cuaderno de Viajes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"xaouen archivos - Cuaderno de Viajes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Cuaderno de Viajes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/tag\\\/xaouen-en\\\/\",\"url\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/tag\\\/xaouen-en\\\/\",\"name\":\"xaouen archivos - Cuaderno de Viajes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/tag\\\/xaouen-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/tag\\\/xaouen-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cover Page\",\"item\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"xaouen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/\",\"name\":\"Cuaderno de Viajes\",\"description\":\"An open window to the World\",\"publisher\":{\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/#\\\/schema\\\/person\\\/d6a50ddc615c616c6b8937937bd6b9cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/anamoralesblog.com\\\/en\\\/#\\\/schema\\\/person\\\/d6a50ddc615c616c6b8937937bd6b9cb\",\"name\":\"Ana Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.anamoralesblog.com\\\/wp-content\\\/uploads\\\/Logo-Cuaderno-Viajes.png\",\"url\":\"https:\\\/\\\/www.anamoralesblog.com\\\/wp-content\\\/uploads\\\/Logo-Cuaderno-Viajes.png\",\"contentUrl\":\"https:\\\/\\\/www.anamoralesblog.com\\\/wp-content\\\/uploads\\\/Logo-Cuaderno-Viajes.png\",\"width\":1630,\"height\":890,\"caption\":\"Ana Morales\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.anamoralesblog.com\\\/wp-content\\\/uploads\\\/Logo-Cuaderno-Viajes.png\"},\"description\":\"Ana Morales en Google+\",\"sameAs\":[\"https:\\\/\\\/www.anamoralesblog.com\",\"https:\\\/\\\/facebook.com\\\/CuadernoViajes\",\"https:\\\/\\\/instagram.com\\\/anamoviajes\",\"https:\\\/\\\/pinterest\\\/cuadernodeviajes\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"xaouen archivos - Cuaderno de Viajes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/","og_locale":"en_US","og_type":"article","og_title":"xaouen archivos - Cuaderno de Viajes","og_url":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/","og_site_name":"Cuaderno de Viajes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/","url":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/","name":"xaouen archivos - Cuaderno de Viajes","isPartOf":{"@id":"https:\/\/anamoralesblog.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/anamoralesblog.com\/en\/tag\/xaouen-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cover Page","item":"https:\/\/anamoralesblog.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"xaouen"}]},{"@type":"WebSite","@id":"https:\/\/anamoralesblog.com\/en\/#website","url":"https:\/\/anamoralesblog.com\/en\/","name":"Cuaderno de Viajes","description":"An open window to the World","publisher":{"@id":"https:\/\/anamoralesblog.com\/en\/#\/schema\/person\/d6a50ddc615c616c6b8937937bd6b9cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anamoralesblog.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/anamoralesblog.com\/en\/#\/schema\/person\/d6a50ddc615c616c6b8937937bd6b9cb","name":"Ana Morales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.anamoralesblog.com\/wp-content\/uploads\/Logo-Cuaderno-Viajes.png","url":"https:\/\/www.anamoralesblog.com\/wp-content\/uploads\/Logo-Cuaderno-Viajes.png","contentUrl":"https:\/\/www.anamoralesblog.com\/wp-content\/uploads\/Logo-Cuaderno-Viajes.png","width":1630,"height":890,"caption":"Ana Morales"},"logo":{"@id":"https:\/\/www.anamoralesblog.com\/wp-content\/uploads\/Logo-Cuaderno-Viajes.png"},"description":"Ana Morales en Google+","sameAs":["https:\/\/www.anamoralesblog.com","https:\/\/facebook.com\/CuadernoViajes","https:\/\/instagram.com\/anamoviajes","https:\/\/pinterest\/cuadernodeviajes"]}]}},"_links":{"self":[{"href":"https:\/\/anamoralesblog.com\/en\/wp-json\/wp\/v2\/tags\/5009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anamoralesblog.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/anamoralesblog.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/anamoralesblog.com\/en\/wp-json\/wp\/v2\/posts?tags=5009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}